{"id":12150,"date":"2020-04-02T05:45:58","date_gmt":"2020-04-02T05:45:58","guid":{"rendered":"http:\/\/www.iglesiamontededios.org.do\/deboras\/?p=12150"},"modified":"2020-04-01T23:22:03","modified_gmt":"2020-04-01T23:22:03","slug":"declare-que-vous-avez-une-foi-2","status":"publish","type":"post","link":"https:\/\/www.iglesiamontededios.org.do\/deboras\/declare-que-vous-avez-une-foi-2\/","title":{"rendered":"D\u00e9clare que vous avez une foi"},"content":{"rendered":"<p>[vc_row][vc_column width=\u00bb2\/3&#8243;][vc_column_text]<strong><img loading=\"lazy\" class=\"alignnone wp-image-9071\" src=\"https:\/\/www.iglesiamontededios.org.do\/deboras\/wp-content\/uploads\/2018\/10\/arte-de-Devocional-frances-300x107.png\" alt=\"\" width=\"547\" height=\"195\" srcset=\"https:\/\/www.iglesiamontededios.org.do\/deboras\/wp-content\/uploads\/2018\/10\/arte-de-Devocional-frances-300x107.png 300w, https:\/\/www.iglesiamontededios.org.do\/deboras\/wp-content\/uploads\/2018\/10\/arte-de-Devocional-frances-768x273.png 768w, https:\/\/www.iglesiamontededios.org.do\/deboras\/wp-content\/uploads\/2018\/10\/arte-de-Devocional-frances-1024x364.png 1024w\" sizes=\"(max-width: 547px) 100vw, 547px\" \/><\/strong><\/p>\n<p><strong> \u201cCe n&#8217;est pas hors de toute mesure, ce n&#8217;est pas des travaux d&#8217;autrui, que nous nous<br \/>\nglorifions; mais c&#8217;est avec l&#8217;esp\u00e9rance, si votre foi augmente, de grandir encore<br \/>\nd&#8217;avantage parmi vous, selon les limites qui nous sont assign\u00e9es\u2026\u201d 2 Corinthiens 10:15<\/strong><\/p>\n<p>Le manque de foi nous fait perdre ce qui est gagn\u00e9 par Christ, ainsi que \u00eatre conformistes,<br \/>\nen acceptant les choses qui ne sont pas. Par cela, Dieu cherche une g\u00e9n\u00e9ration avec la foi,<br \/>\nqui est agressive, d\u00e9cid\u00e9e et vaillante; qui ne s&#8217;arr\u00eate pas devant les d\u00e9fis du monde et se<br \/>\nmaintient ferme en d\u00e9clarant le Mot.<\/p>\n<p>Nous avons besoin d&#8217;augmenter notre foi, puisque nous aurons au moyen d&#8217;elle un champ<br \/>\nde plus grande action, qui permettra de prendre d&#8217;autres territoires qui sont usurp\u00e9s par<br \/>\nl&#8217;ennemi, mais qu&#8217;ils sont les notres.<\/p>\n<p>D\u00e9veloppons une foi violente, qui cro\u00eetra au milieu des preuves, apr\u00e8s ne pas nous r\u00e9signer<br \/>\n\u00e0 mourir au milieu de celles-ci, mais \u00e0 sortir de chacune. D\u00e9clare que tu as une foi pour<br \/>\natteindre l&#8217;impossible, pour prendre de nouveaux territoires, pour poss\u00e9der la terre de<br \/>\nGos\u00e9n, pour f\u00e9conder et pour te multiplier dans tout.<\/p>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb52px\u00bb][vc_row_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_single_image image=\u00bb9146&#8243; img_size=\u00bbmedium\u00bb onclick=\u00bbcustom_link\u00bb img_link_target=\u00bb_blank\u00bb link=\u00bbhttps:\/\/www.iglesiamontededios.org.do\/deboras\/devocional-diario\/\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/2&#8243;][vc_single_image image=\u00bb9147&#8243; img_size=\u00bbmedium\u00bb onclick=\u00bbcustom_link\u00bb img_link_target=\u00bb_blank\u00bb link=\u00bbhttps:\/\/www.iglesiamontededios.org.do\/deboras\/devotion-quotidienne\/\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=\u00bb1\/3&#8243;][vc_widget_sidebar sidebar_id=\u00bbside_frances\u00bb][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=\u00bb2\/3&#8243;][vc_column_text] \u201cCe n&#8217;est pas hors de toute mesure, ce n&#8217;est pas des travaux d&#8217;autrui, que nous nous glorifions; mais c&#8217;est avec l&#8217;esp\u00e9rance, si votre foi augmente, de grandir encore d&#8217;avantage parmi vous, selon les limites qui nous sont assign\u00e9es\u2026\u201d [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[311],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>D\u00e9clare que vous avez une foi - D\u00e9boras Edificadoras del Reino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.iglesiamontededios.org.do\/deboras\/declare-que-vous-avez-une-foi-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9clare que vous avez une foi - D\u00e9boras Edificadoras del Reino\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column width=\u00bb2\/3&#8243;][vc_column_text] \u201cCe n&#8217;est pas hors de toute mesure, ce n&#8217;est pas des travaux d&#8217;autrui, que nous nous glorifions; mais c&#8217;est avec l&#8217;esp\u00e9rance, si votre foi augmente, de grandir encore d&#8217;avantage parmi vous, selon les limites qui nous sont assign\u00e9es\u2026\u201d [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.iglesiamontededios.org.do\/deboras\/declare-que-vous-avez-une-foi-2\/\" \/>\n<meta property=\"og:site_name\" content=\"D\u00e9boras Edificadoras del Reino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PastoresBogaert\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-02T05:45:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-01T23:22:03+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.iglesiamontededios.org.do\/deboras\/wp-content\/uploads\/2018\/10\/arte-de-Devocional-frances-300x107.png\" \/>\n<meta name=\"author\" content=\"deboras_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PastoresBogaert\" \/>\n<meta name=\"twitter:site\" content=\"@PastoresBogaert\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"deboras_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.iglesiamontededios.org.do\/deboras\/declare-que-vous-avez-une-foi-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.iglesiamontededios.org.do\/deboras\/declare-que-vous-avez-une-foi-2\/\"},\"author\":{\"name\":\"deboras_admin\",\"@id\":\"https:\/\/www.iglesiamontededios.org.do\/deboras\/#\/schema\/person\/22ec2d06354eeca1921596aeb4042ba7\"},\"headline\":\"D\u00e9clare que vous avez une foi\",\"datePublished\":\"2020-04-02T05:45:58+00:00\",\"dateModified\":\"2020-04-01T23:22:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.iglesiamontededios.org.do\/deboras\/declare-que-vous-avez-une-foi-2\/\"},\"wordCount\":303,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.iglesiamontededios.org.do\/deboras\/#organization\"},\"articleSection\":[\"Devfrances\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.iglesiamontededios.org.do\/deboras\/declare-que-vous-avez-une-foi-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.iglesiamontededios.org.do\/deboras\/declare-que-vous-avez-une-foi-2\/\",\"url\":\"https:\/\/www.iglesiamontededios.org.do\/deboras\/declare-que-vous-avez-une-foi-2\/\",\"name\":\"D\u00e9clare que vous avez une foi - D\u00e9boras Edificadoras del Reino\",\"isPartOf\":{\"@id\":\"https:\/\/www.iglesiamontededios.org.do\/deboras\/#website\"},\"datePublished\":\"2020-04-02T05:45:58+00:00\",\"dateModified\":\"2020-04-01T23:22:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.iglesiamontededios.org.do\/deboras\/declare-que-vous-avez-une-foi-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.iglesiamontededios.org.do\/deboras\/declare-que-vous-avez-une-foi-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.iglesiamontededios.org.do\/deboras\/declare-que-vous-avez-une-foi-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.iglesiamontededios.org.do\/deboras\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9clare que vous avez une foi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.iglesiamontededios.org.do\/deboras\/#website\",\"url\":\"https:\/\/www.iglesiamontededios.org.do\/deboras\/\",\"name\":\"D\u00e9boras Edificadoras del Reino\",\"description\":\"D\u00e9boras Iglesia Monte de Dios\",\"publisher\":{\"@id\":\"https:\/\/www.iglesiamontededios.org.do\/deboras\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.iglesiamontededios.org.do\/deboras\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.iglesiamontededios.org.do\/deboras\/#organization\",\"name\":\"Iglesia Monte de Dios\",\"url\":\"https:\/\/www.iglesiamontededios.org.do\/deboras\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.iglesiamontededios.org.do\/deboras\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.iglesiamontededios.org.do\/deboras\/wp-content\/uploads\/2018\/12\/Deboras-Logo-2.png\",\"contentUrl\":\"https:\/\/www.iglesiamontededios.org.do\/deboras\/wp-content\/uploads\/2018\/12\/Deboras-Logo-2.png\",\"width\":620,\"height\":174,\"caption\":\"Iglesia Monte de Dios\"},\"image\":{\"@id\":\"https:\/\/www.iglesiamontededios.org.do\/deboras\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/instagram.com\/pastoresbogaert\",\"http:\/\/www.youtube.com\/tvhorebministries\",\"https:\/\/www.facebook.com\/PastoresBogaert\",\"https:\/\/twitter.com\/PastoresBogaert\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.iglesiamontededios.org.do\/deboras\/#\/schema\/person\/22ec2d06354eeca1921596aeb4042ba7\",\"name\":\"deboras_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.iglesiamontededios.org.do\/deboras\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2022049b1efdbc6a5e2f532d15a889a2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2022049b1efdbc6a5e2f532d15a889a2?s=96&d=mm&r=g\",\"caption\":\"deboras_admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9clare que vous avez une foi - D\u00e9boras Edificadoras del Reino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.iglesiamontededios.org.do\/deboras\/declare-que-vous-avez-une-foi-2\/","og_locale":"es_ES","og_type":"article","og_title":"D\u00e9clare que vous avez une foi - D\u00e9boras Edificadoras del Reino","og_description":"[vc_row][vc_column width=\u00bb2\/3&#8243;][vc_column_text] \u201cCe n&#8217;est pas hors de toute mesure, ce n&#8217;est pas des travaux d&#8217;autrui, que nous nous glorifions; mais c&#8217;est avec l&#8217;esp\u00e9rance, si votre foi augmente, de grandir encore d&#8217;avantage parmi vous, selon les limites qui nous sont assign\u00e9es\u2026\u201d [&hellip;]","og_url":"https:\/\/www.iglesiamontededios.org.do\/deboras\/declare-que-vous-avez-une-foi-2\/","og_site_name":"D\u00e9boras Edificadoras del Reino","article_publisher":"https:\/\/www.facebook.com\/PastoresBogaert","article_published_time":"2020-04-02T05:45:58+00:00","article_modified_time":"2020-04-01T23:22:03+00:00","og_image":[{"url":"http:\/\/www.iglesiamontededios.org.do\/deboras\/wp-content\/uploads\/2018\/10\/arte-de-Devocional-frances-300x107.png"}],"author":"deboras_admin","twitter_card":"summary_large_image","twitter_creator":"@PastoresBogaert","twitter_site":"@PastoresBogaert","twitter_misc":{"Escrito por":"deboras_admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.iglesiamontededios.org.do\/deboras\/declare-que-vous-avez-une-foi-2\/#article","isPartOf":{"@id":"https:\/\/www.iglesiamontededios.org.do\/deboras\/declare-que-vous-avez-une-foi-2\/"},"author":{"name":"deboras_admin","@id":"https:\/\/www.iglesiamontededios.org.do\/deboras\/#\/schema\/person\/22ec2d06354eeca1921596aeb4042ba7"},"headline":"D\u00e9clare que vous avez une foi","datePublished":"2020-04-02T05:45:58+00:00","dateModified":"2020-04-01T23:22:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.iglesiamontededios.org.do\/deboras\/declare-que-vous-avez-une-foi-2\/"},"wordCount":303,"commentCount":0,"publisher":{"@id":"https:\/\/www.iglesiamontededios.org.do\/deboras\/#organization"},"articleSection":["Devfrances"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.iglesiamontededios.org.do\/deboras\/declare-que-vous-avez-une-foi-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.iglesiamontededios.org.do\/deboras\/declare-que-vous-avez-une-foi-2\/","url":"https:\/\/www.iglesiamontededios.org.do\/deboras\/declare-que-vous-avez-une-foi-2\/","name":"D\u00e9clare que vous avez une foi - D\u00e9boras Edificadoras del Reino","isPartOf":{"@id":"https:\/\/www.iglesiamontededios.org.do\/deboras\/#website"},"datePublished":"2020-04-02T05:45:58+00:00","dateModified":"2020-04-01T23:22:03+00:00","breadcrumb":{"@id":"https:\/\/www.iglesiamontededios.org.do\/deboras\/declare-que-vous-avez-une-foi-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.iglesiamontededios.org.do\/deboras\/declare-que-vous-avez-une-foi-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.iglesiamontededios.org.do\/deboras\/declare-que-vous-avez-une-foi-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.iglesiamontededios.org.do\/deboras\/"},{"@type":"ListItem","position":2,"name":"D\u00e9clare que vous avez une foi"}]},{"@type":"WebSite","@id":"https:\/\/www.iglesiamontededios.org.do\/deboras\/#website","url":"https:\/\/www.iglesiamontededios.org.do\/deboras\/","name":"D\u00e9boras Edificadoras del Reino","description":"D\u00e9boras Iglesia Monte de Dios","publisher":{"@id":"https:\/\/www.iglesiamontededios.org.do\/deboras\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.iglesiamontededios.org.do\/deboras\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.iglesiamontededios.org.do\/deboras\/#organization","name":"Iglesia Monte de Dios","url":"https:\/\/www.iglesiamontededios.org.do\/deboras\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.iglesiamontededios.org.do\/deboras\/#\/schema\/logo\/image\/","url":"https:\/\/www.iglesiamontededios.org.do\/deboras\/wp-content\/uploads\/2018\/12\/Deboras-Logo-2.png","contentUrl":"https:\/\/www.iglesiamontededios.org.do\/deboras\/wp-content\/uploads\/2018\/12\/Deboras-Logo-2.png","width":620,"height":174,"caption":"Iglesia Monte de Dios"},"image":{"@id":"https:\/\/www.iglesiamontededios.org.do\/deboras\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/instagram.com\/pastoresbogaert","http:\/\/www.youtube.com\/tvhorebministries","https:\/\/www.facebook.com\/PastoresBogaert","https:\/\/twitter.com\/PastoresBogaert"]},{"@type":"Person","@id":"https:\/\/www.iglesiamontededios.org.do\/deboras\/#\/schema\/person\/22ec2d06354eeca1921596aeb4042ba7","name":"deboras_admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.iglesiamontededios.org.do\/deboras\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2022049b1efdbc6a5e2f532d15a889a2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2022049b1efdbc6a5e2f532d15a889a2?s=96&d=mm&r=g","caption":"deboras_admin"}}]}},"_links":{"self":[{"href":"https:\/\/www.iglesiamontededios.org.do\/deboras\/wp-json\/wp\/v2\/posts\/12150"}],"collection":[{"href":"https:\/\/www.iglesiamontededios.org.do\/deboras\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iglesiamontededios.org.do\/deboras\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iglesiamontededios.org.do\/deboras\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iglesiamontededios.org.do\/deboras\/wp-json\/wp\/v2\/comments?post=12150"}],"version-history":[{"count":1,"href":"https:\/\/www.iglesiamontededios.org.do\/deboras\/wp-json\/wp\/v2\/posts\/12150\/revisions"}],"predecessor-version":[{"id":12151,"href":"https:\/\/www.iglesiamontededios.org.do\/deboras\/wp-json\/wp\/v2\/posts\/12150\/revisions\/12151"}],"wp:attachment":[{"href":"https:\/\/www.iglesiamontededios.org.do\/deboras\/wp-json\/wp\/v2\/media?parent=12150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iglesiamontededios.org.do\/deboras\/wp-json\/wp\/v2\/categories?post=12150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iglesiamontededios.org.do\/deboras\/wp-json\/wp\/v2\/tags?post=12150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}